{"id":3683,"date":"2011-04-06T15:16:08","date_gmt":"2011-04-06T19:16:08","guid":{"rendered":"http:\/\/www.boostiao.com\/portal\/?p=3683"},"modified":"2011-04-06T15:43:39","modified_gmt":"2011-04-06T19:43:39","slug":"circuito-kiko-cabrera-gana-la-primera-puntuable","status":"publish","type":"post","link":"http:\/\/www.boostiao.com\/portal\/2011\/04\/06\/circuito-kiko-cabrera-gana-la-primera-puntuable\/","title":{"rendered":"CIRCUITO>> KIKO CABRERA GANA LA PRIMERA PUNTUABLE!"},"content":{"rendered":"<p>En el Aut\u00f3dromo Mobil 1 se vivi\u00f3 la emoci\u00f3n durante la 1era. Puntuable del Campeonato Nacional de Automovilismo 2011, con una cifra record de participantes en todas las categor\u00edas. <\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8642.jpg\" alt=\"\" \/><\/p>\n<p>El  campe\u00f3n nacional de Automovilismo Kiko Cabrera, gan\u00f3 la categor\u00eda DTS seguido por&#8230;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9336.jpg\" alt=\"\" \/><\/p>\n<p>&#8230;C\u00e9sar Santana y&#8230;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9309.jpg\" alt=\"\" \/><\/p>\n<p>&#8230;.Jacinto Peynado, quienes cruzaron la bandera a cuadros segundo y tercero, respectivamente, durante la primera competencia puntuable de Automovilismo celebrada el pasado domingo en el Aut\u00f3dromo Mobil 1.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9354.jpg\" alt=\"\" \/><\/p>\n<p>Para Kiko no fue nada facil, Pedro Sued quien clasifico segundo, sufri\u00f3 una ponchadura en un neum\u00e1tico lo cual termino con sus esperanzas de un buen resultado en la primera manga, pero en la segunda salio con todo y dio una gran batalla como se ve en esta foto.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8403.jpg\" alt=\"\" \/><\/p>\n<p>En la presentaci\u00f3n oficial, se vio claramente quien es el favorito de los fan\u00e1ticos&#8230;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8583.jpg\" alt=\"\" \/><\/p>\n<p>Peynado andaba volando en las practicas previas al evento, aun con unos problemas luego de la clasificaci\u00f3n subi\u00f3 al podium por tercera vez en las tres fechas que ha participado.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9080.jpg\" alt=\"\" \/><\/p>\n<p>As\u00ed se ve\u00eda el pelot\u00f3n de la DTS y RS desde el fondo de la recta.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8689.jpg\" alt=\"\" \/><\/p>\n<p>Fue interesante ver nuevos proyectos como la CRX de Ronny Suarez&#8230;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9343.jpg\" alt=\"\" \/><\/p>\n<p>&#8230;La Civic EG de Tony Canahuate, que muestra much\u00edsimas mejoras.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8329.jpg\" alt=\"\" \/><\/p>\n<p>Y la &#8220;Viejita&#8221;, la Civic EK de Jose Ricardo Leroux que participo con el fin de acumular puntos en lo que recibe su nuevo Accord para la segunda fecha.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9294.jpg\" alt=\"\" \/><\/p>\n<p>El piloto Harold Robles de Santiago en su tercera carrera de circuito, logr\u00f3 el primer lugar de la categor\u00eda RS&#8230;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9362.jpg\" alt=\"\" \/><\/p>\n<p>&#8230;seguido por Robert Bret\u00f3n en segundo, mientras que en tercer puesto llegaba Sebasti\u00e1n Paniagua junto a Julio NG.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8512.jpg\" alt=\"\" \/><\/p>\n<p>Sebastian Paniagua hizo la pole en la RS y domino la primera manga&#8230;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8519.jpg\" alt=\"\" \/><\/p>\n<p>&#8230;aunque con sus problemitas, aqu\u00ed se pasaba de frenada.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9232.jpg\" alt=\"\" \/><\/p>\n<p>El d\u00fao de Victor Gonzalez y Jose Manuel Hernandez confrontaron problemas de neum\u00e1ticos en su Honda Civic en ambas mangas&#8230;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_9508.jpg\" alt=\"\" \/><\/p>\n<p>Definitivamente esto arruino su fin de semana, este fue un problema para varios autos en esta primera fecha.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8329.jpg\" alt=\"\" \/><\/p>\n<p>Alain Giraldi gan\u00f3 las dos mangas saliendo tercero y domino desde la primera vuelta la categor\u00eda ST, seguido por  William Garc\u00eda quien cruz\u00f3 la meta en segundo lugar y Lennin Hern\u00e1ndez quien subi\u00f3 al podium por primera vez al lograr el tercer lugar de esta categor\u00edas donde compitieron 41 carros.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8901.jpg\" alt=\"\" \/><\/p>\n<p>Aunque no subio al podium, Erich Llibre hizo una remontada fabulosa viniendo desde la ultima posici\u00f3n y llegando 3ro en la primera manga.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8965.jpg\" alt=\"\" \/><\/p>\n<p>La &#8220;Nascar Dominicana&#8221; como se le a llamado a la ST dejo saber el porque de su apodo, varios autos chocados y en ocasiones sin espacio para rebasar!<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8772.jpg\" alt=\"\" \/><\/p>\n<p>Sebasti\u00e1n Paniagua domin\u00f3 desde la \u201cPole Position\u201d, en la categor\u00eda Turismo Nacional, seguido de Rafael Luciano, \u201cLa Garza\u201d quien dio una carrera bien competitiva, mientras que el campe\u00f3n reinante, Juan \u201cEl Chino\u201d Lantigua junto Jimmy Cabrera , llegaron en tercer lugar.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8843.jpg\" alt=\"\" \/><\/p>\n<p>El Pace car mas pepillo que ha pasado por el AM1!<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/04\/auto_1ra_640\/IMG_8703.jpg\" alt=\"\" \/><\/p>\n<p>Los Drifters llevaron sus autos para exhibirlos y anunciar el Round 1 de la Serie Dominicana de Drift que sera este pr\u00f3ximo 10 de Abril.<\/p>\n<p>El Aut\u00f3dromo Mobil 1 cuenta este a\u00f1o con seis pruebas puntuables de automovilismo, cuatro de motociclismo, cuatro de dragueo, cinco de drift, cinco de kartismo y los esperados track days y calentones de dragueo, m\u00e1s los eventos internacionales, el Aut\u00f3dromo Mobil 1 se convierte en una opci\u00f3n muy atractiva de diversi\u00f3n<\/p>\n<p>El Campeonato Nacional de Automovilismo organizado por el Aut\u00f3dromo Mobil 1 cuenta con el aval del Club Dominicano de Corredores de Circuito y la fiscalizaci\u00f3n de la Federaci\u00f3n Dominicana de Automovilismo iniciando. Con una inversi\u00f3n de 42 millones de pesos el Aut\u00f3dromo Mobil 1 se avoca a una nueva etapa en los deportes de velocidad, retornando la confianza de los patrocinadores con el apoyo de las marcas como: Lubricantes Mobil, Presidente, Toyota, Banco Popular, Pizza Hut, Induveca, 911, Samsung, Claro y Gomas Michel\u00edn.<\/p>\n<div class=\"fblikebutton_button\" style=\"float: right; margin-left: 10px;\"><iframe src=\"http:\/\/www.facebook.com\/plugins\/like.php?href=http%3A%2F%2Fwww.boostiao.com%2Fportal%2F2011%2F04%2F06%2Fcircuito-kiko-cabrera-gana-la-primera-puntuable%2F&amp;layout=standard&amp;show-faces=true&amp;width=450&amp;action=like&amp;colorscheme=light\" scrolling=\"no\" frameborder=\"0\" allowTransparency=\"true\" style=\"border:none; overflow:hidden; width:450px; height:26px\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el Aut\u00f3dromo Mobil 1 se vivi\u00f3 la emoci\u00f3n durante la 1era. Puntuable del Campeonato Nacional de Automovilismo 2011, con una cifra record de participantes en todas las categor\u00edas. El campe\u00f3n nacional de Automovilismo Kiko Cabrera, gan\u00f3 la categor\u00eda DTS seguido por&#8230; &#8230;C\u00e9sar Santana y&#8230; &#8230;.Jacinto Peynado, quienes cruzaron la bandera a cuadros segundo y tercero, respectivamente, durante la primera competencia puntuable de Automovilismo celebrada el pasado domingo en el Aut\u00f3dromo Mobil 1. Para Kiko no fue nada facil, Pedro Sued quien clasifico segundo, sufri\u00f3 una ponchadura en un neum\u00e1tico lo cual termino con sus esperanzas de un buen resultado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7,11,10],"tags":[1346,573,57,1343,661,1349,192,519,558,229,1344,440,228,560,880,565,58,938,1070,1347,1348,1345,569],"class_list":["post-3683","post","type-post","status-publish","format-standard","hentry","category-circuito","category-generales","category-internacionales","tag-automovilimos","tag-cesar-santana","tag-dts","tag-el-chino","tag-erich-llibre","tag-harold-robles","tag-jacinto-peynado","tag-jose-ricardo-leroux","tag-juan-lantigua","tag-kiko-cabrera","tag-la-garza","tag-mazda","tag-pedro-sued","tag-rafael-luciano","tag-robert-breton","tag-ronny-suarez","tag-rs","tag-seat","tag-sebastian-paniagua","tag-st","tag-tn","tag-tomas-urbaez","tag-tony-canahuate"],"_links":{"self":[{"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/posts\/3683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/comments?post=3683"}],"version-history":[{"count":5,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/posts\/3683\/revisions"}],"predecessor-version":[{"id":3688,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/posts\/3683\/revisions\/3688"}],"wp:attachment":[{"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/media?parent=3683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/categories?post=3683"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/tags?post=3683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}