{"id":4519,"date":"2011-11-15T13:57:09","date_gmt":"2011-11-15T17:57:09","guid":{"rendered":"http:\/\/www.boostiao.com\/portal\/?p=4519"},"modified":"2011-11-15T14:13:54","modified_gmt":"2011-11-15T18:13:54","slug":"circuito-paul-oneil-de-la-serie-btcc-viene-a-la-dts-con-2t-motorsports","status":"publish","type":"post","link":"http:\/\/www.boostiao.com\/portal\/2011\/11\/15\/circuito-paul-oneil-de-la-serie-btcc-viene-a-la-dts-con-2t-motorsports\/","title":{"rendered":"CIRCUITO>> PAUL O&#8217;NEILL, DE LA SERIE BTCC, VIENE A LA DTS CON 2T MOTORSPORTS"},"content":{"rendered":"<p>El renombrado piloto brit\u00e1nico Paul O\u2019Neall, de la serie British Touring Car Championship (BTCC), ver\u00e1 acci\u00f3n junto al equipo 2T Motorsport, en la sexta y \u00faltima prueba puntuable del Campeonato Nacional de Automovilismo, a celebrarse el domingo 4 de diciembre en el Aut\u00f3dromo Mobil 1.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/11\/2t\/2t2.jpg\" alt=\"\" \/><\/p>\n<p>Los  volantes criollos Jos\u00e9-Tonino-Aybar y Tony Gonz\u00e1lez, l\u00edderes de 2T Motorsport, revelaron que est\u00e1n dando los \u00faltimos toques para llegada al pa\u00eds del brit\u00e1nico O\u2019Neall, quien viene a reforzar los esfuerzos que hace la escuder\u00eda por andar en los primeros lugares del esperado certamen de velocidad.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/11\/2t\/paul.jpg\" alt=\"\" \/><\/p>\n<p>El team anunci\u00f3 que solo espera por la confirmaci\u00f3n del legendario piloto, quien en su pa\u00eds perteneciera al equipo Vauxhall y el team Dynamics de la BTCC, donde logr\u00f3 ganar importantes carreras a bordo del Honda Integra que ahora pertenece al equipo criollo.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/11\/2t\/milo.jpg\" alt=\"\" \/><\/p>\n<p>Al mismo tiempo, 2T Motorsport anunci\u00f3 que el Costarricense Emilio-Milo- Valverde, quien conquist\u00f3 la pole position compitiendo para ese equipo en la pasada puntuable, podr\u00eda estar nuevamente en suelo dominicano.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/11\/2t\/2t.jpg\" alt=\"\" \/><\/p>\n<p>2T Motorsport ha sido un equipo pujante en cuanto a la presencia de destacados pilotos internacionales en el actual campeonato, ya que en el pasado evento ese equipo trajo al pa\u00eds al sensacional Valverde, quien tuvo una destacada participaci\u00f3n ganando la posici\u00f3n de polo en esa oportunidad, a bordo del moderno Honda Integra, que fuera campe\u00f3n en la serie BTCC brit\u00e1nica.<\/p>\n<p>\u201cNuestra meta en la venidera competencia es volver a conquistar la pole position, y porqu\u00e9 no, conquistar la bandera a cuadros de la categor\u00eda Dominican Touring Series (DTS), que un fallo el\u00e9ctrico nos neg\u00f3 la vez anterior\u201d, dijeron Aybar y Gonz\u00e1lez, por medio de un despacho de prensa.<\/p>\n<p>El equipo 2T,  que captur\u00f3 toda la atenci\u00f3n en su debut al traer al pa\u00eds el moderno Honda Integra, se prepara sin descanso con miras a conquistar el certamen de cierre del campeonato 2011, en el cual accionar\u00e1n destacados pilotos locales y extranjeros.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.boostiao.com\/portal\/wp-content\/uploads\/2011\/09\/4ta_autos_640\/IMG_0621.jpg\" alt=\"\" \/><\/p>\n<p>Aybar  y Gonz\u00e1lez reiteraron  su compromiso de llevar la escuder\u00eda 2T Motorsport a lo m\u00e1s alto del p\u00f3dium, ya que consideran que de los autos que conforman la parrilla en la DTS, su  Honda Integra tra\u00eddo desde Inglaterra, posee el mejor paquete tecnol\u00f3gico.<\/p>\n<p>\u201cEl Integra de nuestro equipo est\u00e1 cada d\u00eda mejor en la pista y queremos demostrar que es solo cuesti\u00f3n de \u2018seteo\u2019 para que est\u00e1 en la punta al final de la largada\u201d, agregaron. Se\u00f1alaron que de los carros que accionan en la DTS su b\u00f3lido ya demostr\u00f3 que es clase a parte, debido a que conquist\u00f3 la pole con tiempos muy superiores a sus m\u00e1s cercanos rivales en la pasada contienda.<\/p>\n<p>Dijeron que est\u00e1n enfocados en ganar la \u00faltima puntuable, \u201cy con tal objetivo estamos trayendo al pa\u00eds pilotos mucho m\u00e1s experimentados, que nos ayuden con el seteo y a la vez mostrarle a ellos los avances de nuestro automovilismo, lo cual al final redunda en beneficio del p\u00fablico que asiste a cada competencia\u201d.<\/p>\n<div class=\"fblikebutton_button\" style=\"float: right; margin-left: 10px;\"><iframe src=\"http:\/\/www.facebook.com\/plugins\/like.php?href=http%3A%2F%2Fwww.boostiao.com%2Fportal%2F2011%2F11%2F15%2Fcircuito-paul-oneil-de-la-serie-btcc-viene-a-la-dts-con-2t-motorsports%2F&amp;layout=standard&amp;show-faces=true&amp;width=450&amp;action=like&amp;colorscheme=light\" scrolling=\"no\" frameborder=\"0\" allowTransparency=\"true\" style=\"border:none; overflow:hidden; width:450px; height:26px\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El renombrado piloto brit\u00e1nico Paul O\u2019Neall, de la serie British Touring Car Championship (BTCC), ver\u00e1 acci\u00f3n junto al equipo 2T Motorsport, en la sexta y \u00faltima prueba puntuable del Campeonato Nacional de Automovilismo, a celebrarse el domingo 4 de diciembre en el Aut\u00f3dromo Mobil 1. Los volantes criollos Jos\u00e9-Tonino-Aybar y Tony Gonz\u00e1lez, l\u00edderes de 2T Motorsport, revelaron que est\u00e1n dando los \u00faltimos toques para llegada al pa\u00eds del brit\u00e1nico O\u2019Neall, quien viene a reforzar los esfuerzos que hace la escuder\u00eda por andar en los primeros lugares del esperado certamen de velocidad. El team anunci\u00f3 que solo espera por la confirmaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7,11,10],"tags":[1426,1687,1688,1686,1058],"class_list":["post-4519","post","type-post","status-publish","format-standard","hentry","category-circuito","category-generales","category-internacionales","tag-2t-motorsports","tag-honda-integra","tag-miguel-martinez","tag-paul-oneill","tag-tonino-aybar"],"_links":{"self":[{"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/posts\/4519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/comments?post=4519"}],"version-history":[{"count":6,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/posts\/4519\/revisions"}],"predecessor-version":[{"id":4523,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/posts\/4519\/revisions\/4523"}],"wp:attachment":[{"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/media?parent=4519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/categories?post=4519"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.boostiao.com\/portal\/wp-json\/wp\/v2\/tags?post=4519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}